{"id":3104,"date":"2022-05-11T03:16:09","date_gmt":"2022-05-11T03:16:09","guid":{"rendered":"http:\/\/test.loc\/?page_id=3100"},"modified":"2025-11-11T01:27:53","modified_gmt":"2025-11-10T22:27:53","slug":"contact","status":"publish","type":"page","link":"https:\/\/apl.geoecomar.ro\/euroleasing\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3104\" class=\"elementor elementor-3104\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd15043 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"fd15043\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cab879\" data-id=\"5cab879\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0bb7e84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bb7e84\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1f1eb0f\" data-id=\"1f1eb0f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae22989 elementor-absolute elementor-widget__width-initial elementor-widget elementor-widget-stm-contact-form-seven\" data-id=\"ae22989\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"stm-contact-form-seven.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"stm-elementor-contact-form-seven \" id=\"single_contact_form_62932\">\n\t<div class=\"icon-title\">\n\t\t\t\t\t<h2 class=\"heading-font title\">\n\t\t\t\tCONTACTEAZA-NE\t\t\t<\/h2>\n\t\t\t<\/div>\n\n\t\n\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f717-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"717\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/euroleasing\/wp-json\/wp\/v2\/pages\/3104#wpcf7-f717-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"717\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.2\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f717-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n    <div class=\"col-md-7 col-sm-7\">\n        <div class=\"row\">\n            <div class=\"col-md-6 col-sm-6\">\n                <div class=\"form-group\">\n                    <div class=\"contact-us-label\">Prenume*<\/div>\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Prenumele dumneavoastra\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span>\n                <\/div>\n            <\/div>\n            <div class=\"col-md-6 col-sm-6\">\n                <div class=\"form-group\">\n                    <div class=\"contact-us-label\">Nume*<\/div>\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Numele dumneavoastra\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"row\">\n            <div class=\"col-md-6 col-sm-6\">\n                <div class=\"form-group\">\n                    <div class=\"contact-us-label\">Email*<\/div>\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"email@domain.com\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n                <\/div>\n            <\/div>\n            <div class=\"col-md-6 col-sm-6\">\n                <div class=\"form-group\">\n                    <div class=\"contact-us-label\">Telefon<\/div>\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Numar telefon\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n\n       \n    <\/div>\n\n    <div class=\"col-md-5 col-sm-5\">\n        <div class=\"form-group\">\n            <div class=\"form-group\">\n                <div class=\"contact-us-label\">Mesaj<\/div>\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Scrieti mesajul dumneavoastra...\" name=\"message\"><\/textarea><\/span>\n            <\/div>\n        <\/div>\n        <div class=\"contact-us-submit\">\n            <input class=\"wpcf7-form-control wpcf7-submit has-spinner contact-us-submit\" type=\"submit\" value=\"Trimite\" \/>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51b8b43 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"51b8b43\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-11ee9bf\" data-id=\"11ee9bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d970ae elementor-widget elementor-widget-motors-contact-tabs\" data-id=\"4d970ae\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"motors-contact-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"stm-elementor-contact-tabs\">\n\t\t<div class=\"elementor-contact-tabs\">\n\t\t\t<div class=\"elementor-contact-tabs-container\">\n\t\t\t\t<ul class=\"elementor-contact-tabs-list\">\n\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-contact-tab active\" data-tab=\"765560\">\n\t\t\t\t\t\t<span class=\"tab-item\">\n\t\t\t\t\t\t\t<span class=\"elementor-contact-title-text\">\n\t\t\t\t\t\t\t\tContact\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<div class=\"contact-tabs-containers-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-contact-panels-container contact-panel-765560 active\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tab-unit\">\n\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stmicon- stm-icon-pin\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<h4 class=\"title heading-font\">\n\t\t\t\t\t\t\t\t\tAdresa\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<div class=\"content heading-font\">\n\t\t\t\t\t\t\t\t\t<div class=\"icon-box vc_custom_1447842696775 icon_box_63500 stm-layout-box-car_dealer \"><p>\u00a0<\/p><div class=\"icon-text\"><div class=\"content heading-font\"><p><span class=\"heading-font\">Splaiul Unirii 865H Bucuresti, Sector 3, 077160<\/span><\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tab-unit\">\n\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stmicon- stm-icon-phone\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<h4 class=\"title heading-font\">\n\t\t\t\t\t\t\t\t\tTelefon\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<div class=\"content heading-font\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>+40753 222 221<\/p><p>+40745 991 418<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tab-unit\">\n\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stmicon- stm-icon-time\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<h4 class=\"title heading-font\">\n\t\t\t\t\t\t\t\t\tProgram\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<div class=\"content heading-font\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"date\">Luni \u2013 Vineri:<\/span> 09:00 \u2013 19:00<br \/><span class=\"date\">Sambata:<\/span> 09:00 \u2013 17:00<br \/><span class=\"date\">Duminica:<\/span> 10:00 \u2013 14:00<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-c583530\" data-id=\"c583530\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d286839 elementor-widget elementor-widget-html\" data-id=\"d286839\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2850.8226695506796!2d26.188352077338312!3d44.395761804087236!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x40b1fda0214f8f37%3A0x88be0b195059a714!2sEuro%20Leasing!5e0!3m2!1sen!2sro!4v1761131317248!5m2!1sen!2sro\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CONTACTEAZA-NE Prenume* Nume* Email* Telefon Mesaj Contact Adresa \u00a0 Splaiul Unirii 865H Bucuresti, Sector 3, 077160 Telefon \u00a0 +40753 222 221 +40745 991 418 Program Luni \u2013 Vineri: 09:00 \u2013 19:00Sambata: 09:00 \u2013 17:00Duminica: 10:00 \u2013 14:00<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-3104","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/apl.geoecomar.ro\/euroleasing\/wp-json\/wp\/v2\/pages\/3104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apl.geoecomar.ro\/euroleasing\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apl.geoecomar.ro\/euroleasing\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apl.geoecomar.ro\/euroleasing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apl.geoecomar.ro\/euroleasing\/wp-json\/wp\/v2\/comments?post=3104"}],"version-history":[{"count":0,"href":"https:\/\/apl.geoecomar.ro\/euroleasing\/wp-json\/wp\/v2\/pages\/3104\/revisions"}],"wp:attachment":[{"href":"https:\/\/apl.geoecomar.ro\/euroleasing\/wp-json\/wp\/v2\/media?parent=3104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}